{"id":78592,"date":"2022-10-01T23:49:55","date_gmt":"2022-10-02T02:49:55","guid":{"rendered":"https:\/\/filmesporno.net.br\/?p=78592"},"modified":"2022-10-01T23:49:55","modified_gmt":"2022-10-02T02:49:55","slug":"xi-videos-dotado-fodendo-duas-putas-taradas","status":"publish","type":"post","link":"https:\/\/filmesporno.net.br\/xi-videos-dotado-fodendo-duas-putas-taradas\/","title":{"rendered":"Xi videos dotado fodendo duas putas taradas"},"content":{"rendered":"Xi videos dotado fodendo duas putas taradas. Uma putaria de primeira, com um marmanjo do pau grande e grosso pegando duas putinhas lindas e taradas e fazendo de tudo com elas. O cara bota as duas safadas submissas pra chupar seu pauz\u00e3o e deixar ele bem babado. Depois ele come a buceta e o cu das duas, que gemem e sorriem com o pau entrando. ","protected":false},"excerpt":{"rendered":"<p>Xi videos dotado fodendo duas putas taradas. Uma putaria de primeira, com um marmanjo do pau grande e grosso pegando duas putinhas lindas e taradas e fazendo de tudo com elas. O cara bota as duas safadas submissas pra chupar seu pauz\u00e3o e deixar ele bem babado. Depois ele come a buceta e o cu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":78593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[201],"tags":[],"class_list":["post-78592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-xvideos"],"_links":{"self":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/posts\/78592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/comments?post=78592"}],"version-history":[{"count":0,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/posts\/78592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/media\/78593"}],"wp:attachment":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/media?parent=78592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/categories?post=78592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/tags?post=78592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}