{"id":87906,"date":"2023-07-04T10:25:29","date_gmt":"2023-07-04T13:25:29","guid":{"rendered":"https:\/\/filmesporno.net.br\/?p=87906"},"modified":"2023-07-04T10:25:29","modified_gmt":"2023-07-04T13:25:29","slug":"novinha-safada-fazendo-a-sua-dupla-penetracao","status":"publish","type":"post","link":"https:\/\/filmesporno.net.br\/novinha-safada-fazendo-a-sua-dupla-penetracao\/","title":{"rendered":"Novinha safada fazendo a sua dupla penetra\u00e7\u00e3o"},"content":{"rendered":"Essa branquinha est\u00e1 querendo fazer algo diferente, ela quer sentir uma rola entrando na sua buceta e outra no seu cuzinho, ela ent\u00e3o come\u00e7a a ati\u00e7ar dois rapazes que levam ela pro quarto. L\u00e1 eles ficam todos pelados e ela come\u00e7a a chupar os dois juntos e j\u00e1 fica de ladinho, um j\u00e1 come\u00e7a a aquecer a sua xotinha pra depois o outro chegar no cu.","protected":false},"excerpt":{"rendered":"<p>Essa branquinha est\u00e1 querendo fazer algo diferente, ela quer sentir uma rola entrando na sua buceta e outra no seu cuzinho, ela ent\u00e3o come\u00e7a a ati\u00e7ar dois rapazes que levam ela pro quarto. L\u00e1 eles ficam todos pelados e ela come\u00e7a a chupar os dois juntos e j\u00e1 fica de ladinho, um j\u00e1 come\u00e7a a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":87907,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-87906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dupla-penetracao"],"_links":{"self":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/posts\/87906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/comments?post=87906"}],"version-history":[{"count":0,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/posts\/87906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/media\/87907"}],"wp:attachment":[{"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/media?parent=87906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/categories?post=87906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filmesporno.net.br\/wp-json\/wp\/v2\/tags?post=87906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}